{"id":1319,"date":"2022-07-21T18:43:20","date_gmt":"2022-07-21T15:43:20","guid":{"rendered":"http:\/\/www.albadental.com.tr\/behandlungen\/porzellan-furnier\/"},"modified":"2023-07-31T15:21:07","modified_gmt":"2023-07-31T12:21:07","slug":"porzellan-furnier","status":"publish","type":"page","link":"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/","title":{"rendered":"Porzellan-Furnier"},"content":{"rendered":"\n\t<section class=\"section p-font-size-14px\" id=\"section_1057918828\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-434894458\">\n\n\t<div id=\"col-2114773329\" class=\"col medium-5 small-12 large-5\"  >\n\t\t<div class=\"is-sticky-column\"><div class=\"is-sticky-column__inner\">\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-796051207\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1178591825\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-3570516154\" class=\"text\">\n\t\t\n<h2 class=\"uppercase\"><strong>Zirkonium Krone<\/strong><\/h2>\n\t\t\n<style>\n#text-3570516154 {\n  font-size: 0.75rem;\n}\n@media (min-width:550px) {\n  #text-3570516154 {\n    font-size: 1rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1178591825 {\n  width: 100%;\n}\n#text-box-1178591825 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1178591825 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-796051207 {\n  padding-top: 84vh;\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row\"  id=\"row-1590368928\">\n\n\t<div id=\"col-231092169\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a class=\"button primary lowercase expand\"  >\n\t\t<span>WhatsApp<\/span>\n\t<i class=\"icon-clock\" aria-hidden=\"true\" ><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-120451435\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<a class=\"button secondary lowercase expand\"  >\n\t\t<span>Ernennung<\/span>\n\t<i class=\"icon-clock\" aria-hidden=\"true\" ><\/i><\/a>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row\"  id=\"row-2084732261\">\n\n\t<div id=\"col-1607444830\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div id=\"twenty20-1\" class=\"twenty20\" style=\"width: 100% !important; clear: both; float: right; margin-left: 20px;\"><div class=\"twentytwenty-container twenty20-1 \"><img decoding=\"async\" src=\"https:\/\/www.albadental.com.tr\/wp-content\/uploads\/2022\/07\/website6.jpg\" alt=\"Before image\" \/><img decoding=\"async\" src=\"https:\/\/www.albadental.com.tr\/wp-content\/uploads\/2022\/07\/website5.jpg\" alt=\"After image\" \/><\/div><\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1020161464\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1618524542\" class=\"text\">\n\t\t\n<div class=\"title-block\">\n<h4>ALBA DENT ADSP<\/h4>\n<h1 class=\"uppercase\">Porzellan-Furnier<\/h1>\n<\/div>\n\t\t\n<style>\n#text-1618524542 {\n  text-align: left;\n}\n@media (min-width:550px) {\n  #text-1618524542 {\n    text-align: left;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-575656868\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-575656868 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2531576308\" class=\"text\">\n\t\t\n<p>Porzellan Krone verleiht Ihnen ein w\u00e4rmeres L\u00e4cheln. Dein L\u00e4cheln ist das erste, was andere als dein eigenes sehen. Wenn Sie Ihren Z\u00e4hnen oder der Farbe Ihrer Z\u00e4hne nicht vertrauen, k\u00f6nnen Sie m\u00f6glicherweise nicht so l\u00e4cheln, wie Sie es m\u00f6chten. Infolgedessen k\u00f6nnen Sie sich m\u00f6glicherweise nicht genau so ausdr\u00fccken, wie Sie es m\u00f6chten, und Sie wirken m\u00f6glicherweise weniger gl\u00fccklich oder weniger mitf\u00fchlend als Sie sind. Laminierte Zahn Krone ver\u00e4ndern das Aussehen Ihres L\u00e4chelns und Ihrer Z\u00e4hne mit ihrer Best\u00e4ndigkeit, die Jahrzehnte dauern kann.   <\/p>\n<p> Alle Kerben, Flecken, L\u00fccken, Fehlstellungen und andere Probleme, die Sie an Ihren Z\u00e4hnen nicht m\u00f6gen, k\u00f6nnen alle mit laminierten Zahnveneers effektiv entfernt werden. Mit diesen fortschrittlichen Behandlungsoptionen bestimmen unsere Zahn\u00e4rzte das Design Ihrer Z\u00e4hne in einem einzigen Besuch und k\u00f6nnen sie auf Ihren Wunsch sogar in einer einzigen Sitzung erneuern <\/p>\n<p>Bei Ihrem ersten Termin k\u00f6nnen Sie Ihre Anliegen und W\u00fcnsche bedenkenlos mit Ihrem Zahnarzt besprechen und Behandlungspl\u00e4ne erstellen. Um mehr \u00fcber laminierte Beschichtungen, also Blattbeschichtungen und deren Preise zu erfahren, k\u00f6nnen Sie uns unter unserer Nummer kontaktieren oder das Online-Terminformular ausf\u00fcllen.<br \/>\n\t\t\n<style>\n#text-2531576308 {\n  text-align: left;\n}\n@media (min-width:550px) {\n  #text-2531576308 {\n    text-align: left;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-205582940\">\n\n\t<div id=\"col-299898727\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-111237501\" class=\"text\">\n\t\t\n<h3>Porzellan Kronen und Details<\/h3>\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p>Porzellan-Kronen sind sehr d\u00fcnne Porzellanst\u00fccke, die auf die Vorderseite der Z\u00e4hne geklebt werden, um ein angenehmes und glattes L\u00e4cheln zu bieten, ohne das nat\u00fcrliche Aussehen der Z\u00e4hne zu beeintr\u00e4chtigen, und um die gleiche <strong>Festigkeit und Flexibilit\u00e4t<\/strong> wie nat\u00fcrlicher Zahnschmelz zu bieten. F\u00fcr die Verklebung der Veneers werden die Frontfl\u00e4chen der Z\u00e4hne um ca. 0,5 mm ausged\u00fcnnt. <strong>Dann wird das Porzellanmaterial<\/strong> auf die Z\u00e4hne geklebt und der Vorgang ist abgeschlossen. Laminierte Kronen sind im Allgemeinen die bevorzugten Materialien f\u00fcr diejenigen, die leichte Positions\u00e4nderungen vornehmen oder die Form, Gr\u00f6\u00dfe und Farbe der Z\u00e4hne \u00e4ndern m\u00f6chten. Dieses Material besteht aus mehreren d\u00fcnnen Keramikschichten und einer Haftschicht, die den urspr\u00fcnglichen Zahnschmelz ersetzt. W\u00e4hrend der <strong>Operation sind keine Schmerzen zu sp\u00fcren<\/strong>. Da Laminatveneers eine sehr d\u00fcnne Schicht sind, sind sie eine sehr zufriedenstellende Option, insbesondere wenn Farbe, Form und unerw\u00fcnschte Konturen auf den urspr\u00fcnglichen Z\u00e4hnen auftreten. Wenn oberfl\u00e4chliche Verf\u00e4rbungen nicht gut auf Bleaching oder Bleaching ansprechen, sind laminierte Furniere m\u00f6glicherweise die <strong>beste Option<\/strong>. Sie k\u00f6nnen unsere Klinik von jedem Kanal aus kontaktieren, um Informationen \u00fcber den Preis und die Anwendung zu erhalten.        <\/p>\n<\/div>\n<\/div>\n\t\t\n<style>\n#text-111237501 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3533124541\" class=\"text\">\n\t\t\n<h3>Vorteile von Lamina-Porzellan Kronen<\/h3>\n<ul>\n<li>Verbessertes Erscheinungsbild von asymmetrischen, kurzen, gebrochenen oder abgenutzten Z\u00e4hnen<\/li>\n<li>Korrektur von Hohlr\u00e4umen, Frontzahnspaltungen und Fehlstellungen<\/li>\n<li>Korrektur des Aussehens extrem dunkler Z\u00e4hne, f\u00fcr die die Zahnaufhellungsmethode nicht ausreicht<\/li>\n<li>Reduzierung von Zahnflecken und Verf\u00e4rbungen<\/li>\n<li>Verschlei\u00dffeste Zahnstruktur<\/li>\n<li>Langanhaltende Ergebnisse, die zuk\u00fcnftigen Flecken oder Vergilbungen widerstehen<\/li>\n<li>evitalisierte Ansicht vorhandener Zahnrestaurationen wie Zahnkronen und -br\u00fccken<\/li>\n<li>Personalisierter Behandlungsplan f\u00fcr ein m\u00f6glichst nat\u00fcrliches Erscheinungsbild und eine m\u00f6glichst bequeme Passform<\/li>\n<\/ul>\n\t\t\n<style>\n#text-3533124541 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-equal align-center\"  id=\"row-1237072474\">\n\n\t<div id=\"col-46217713\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(234, 234, 234);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1379110052\" class=\"text\">\n\t\t\n<h4>F\u00fcr wen ist Porzellan Veneer geeignet?<\/h4>\n<p>Es eignet sich f\u00fcr den Einsatz bei Smile-Design-Verfahren, die mit Aufhellung, Z\u00e4hnen mit schlechter Struktur und Form, alten F\u00fcllungen, gebrochenen, abgenutzten, schiefen oder schiefen Z\u00e4hnen nicht erreicht werden k\u00f6nnen. Mit seiner d\u00fcnnen Blattstruktur kann es auf fast jede Zahnstruktur aufgetragen werden.<br \/>\n\t\t\n<style>\n#text-1379110052 {\n  font-size: 0.85rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-46217713 > .col-inner {\n  padding: 15px 15px 15px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-75235949\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(234, 234, 234);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-3737610980\" class=\"text\">\n\t\t\n<h4>Behandlung Dauer<\/h4>\n<p>1-2 Wochen<br \/>\n\t\t\n<style>\n#text-3737610980 {\n  font-size: 0.85rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-75235949 > .col-inner {\n  padding: 15px 15px 15px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-604835823\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(234, 234, 234);\" >\n\t\t\t\n\t\t\t\n\t<div id=\"text-2021491271\" class=\"text\">\n\t\t\n<h4>Wiederherstellungszeit<\/h4>\n<p>Die meisten Patienten berichten, dass ihre vollst\u00e4ndige Passform mit Porzellan-Kronen und Laminat-Kronen etwa zwei Wochen dauert. Die Operation ist in der ersten Woche abgeschlossen, das Gef\u00fchl und die Funktion nat\u00fcrlicher Z\u00e4hne und Porzellanveneers sollten in der zweiten Woche vollst\u00e4ndig eingestellt sein und es sollte kein Unterschied zwischen ihnen und nat\u00fcrlichen Z\u00e4hnen bestehen.<br \/>\n\t\t\n<style>\n#text-2021491271 {\n  font-size: 0.85rem;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-604835823 > .col-inner {\n  padding: 15px 15px 15px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<h2><span class=\"thb-slidetype-entry\"><span class=\"lines\">H\u00e4ufig gestellte Fragen<br \/>\n<\/span><\/span><\/h2>\n<div class=\"accordion accordion-hizmet\">\n\t<div id=\"accordion-2888012968\" class=\"accordion-item\">\n\t\t<a id=\"accordion-2888012968-label\" class=\"accordion-title plain\" href=\"#accordion-item-werden-blattlamina-veneers-meinen-z\u00e4hnen-schaden?\" aria-expanded=\"false\" aria-controls=\"accordion-2888012968-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Werden Blattlamina-Veneers meinen Z\u00e4hnen schaden?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-2888012968-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-2888012968-label\" >\n\t\t\t\n<p>Nein, Veneers besch\u00e4digen Ihre nat\u00fcrlichen Z\u00e4hne nicht. Sie sind so konzipiert, dass sie zu Ihren Z\u00e4hnen passen und ihr nat\u00fcrlich sch\u00f6nes Aussehen verbessern. Das Kleben von Blattfurnieren bedeutet nicht, dass Ihre Z\u00e4hne besch\u00e4digt oder verletzt werden. Dar\u00fcber hinaus bestehen Porzellanveneers nicht aus dem Zahnschmelz, der die Vorderseite Ihrer Z\u00e4hne bildet. Daher hat es eine l\u00e4ngere Haltbarkeit.    <\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-306578819\" class=\"accordion-item\">\n\t\t<a id=\"accordion-306578819-label\" class=\"accordion-title plain\" href=\"#accordion-item-k\u00f6nnen-veneers-gek\u00fcrzt-werden?\" aria-expanded=\"false\" aria-controls=\"accordion-306578819-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>K\u00f6nnen Veneers gek\u00fcrzt werden?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-306578819-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-306578819-label\" >\n\t\t\t\n<p>Wenn Sie mit den Veneers auf Ihren Z\u00e4hnen nicht zufrieden sind, gibt es M\u00f6glichkeiten, die Veneers anzupassen oder zu ersetzen. Oft k\u00f6nnen Veneers umgeformt werden, um die L\u00e4nge zu verk\u00fcrzen, zu begradigen, die Position des Mundverschlusses anzupassen und die Konturen zu \u00e4ndern. Sie k\u00f6nnen auch in der Gr\u00f6\u00dfe ge\u00e4ndert werden, um sie optisch dicker oder weicher erscheinen zu lassen.  <\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3913279039\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3913279039-label\" class=\"accordion-title plain\" href=\"#accordion-item-wie-viele-jahre-kann-veneer-verwendet-werden?\" aria-expanded=\"false\" aria-controls=\"accordion-3913279039-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Wie viele Jahre kann Veneer verwendet werden?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3913279039-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3913279039-label\" >\n\t\t\t\n<p>Porzellan-Veneers halten in der Regel viele Jahre, dank der richtigen Mundpflege ist die Nutzungsdauer sehr lang. Porzellanstruktur mit Bindematerialqualit\u00e4t und \u00fcberlegenen Eigenschaften bewahrt seine Farbe und Haltbarkeit f\u00fcr viele Jahre. Es gibt viele Patienten mit Veneers, die auch nach 20 Jahren noch toll aussehen. Die Langlebigkeit von Porzellanveneers h\u00e4ngt oft davon ab, wie ein Patient sie nach dem Einsetzen pflegt.   <\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1996794529\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1996794529-label\" class=\"accordion-title plain\" href=\"#accordion-item-wird-lamina-veneer-auf-schiefe-frontz\u00e4hne-aufgetragen?\" aria-expanded=\"false\" aria-controls=\"accordion-1996794529-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Wird Lamina Veneer auf schiefe Frontz\u00e4hne aufgetragen?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1996794529-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1996794529-label\" >\n\t\t\t\n<p>Lamina-Veneers k\u00f6nnen auf alle Z\u00e4hne aufgetragen werden. Wenn Sie zur ersten Sitzung kommen, k\u00f6nnen Sie mit Hilfe der \u00c4rzte \u00fcber das gew\u00fcnschte L\u00e4chelndesign sprechen, und nachdem Sie sich entschieden haben, k\u00f6nnen Sie das \u00e4sthetische Erscheinungsbild erhalten, bei dem Sie die schiefe Zahnstruktur loswerden. Nach dem Behandlungsprozess, der ca. 1 Woche dauert, setzen Sie Ihr Leben mit Ihrer neuen Zahnsubstanz fort.  <\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1682369972\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1682369972-label\" class=\"accordion-title plain\" href=\"#accordion-item-wie-viele-sitzungen-und-wie-lange-dauert-es,-blattlamina-kronen-zu-installieren?\" aria-expanded=\"false\" aria-controls=\"accordion-1682369972-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Wie viele Sitzungen und wie lange dauert es, Blattlamina-Kronen zu installieren?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1682369972-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1682369972-label\" >\n\t\t\t\n<p>Laminiertes Zahn Kronen ist ein Prozess, der je nach Zahnstruktur in 2-3 Sitzungen endet. Innerhalb von 1 Woche werden die Operationen an den Tagen und Daten durchgef\u00fchrt, f\u00fcr die der Patient geeignet ist, und das Ergebnis wird erzielt. <\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3370256149\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3370256149-label\" class=\"accordion-title plain\" href=\"#accordion-item-wie-kann-ich-die-preise-von-laminatzahnfurnieren-erfahren?\" aria-expanded=\"false\" aria-controls=\"accordion-3370256149-content\" >\n\t\t\t<button class=\"toggle\" aria-label=\"Umschalten\"><i class=\"icon-angle-down\"><\/i><\/button>\n\t\t\t<span>Wie kann ich die Preise von Laminatzahnfurnieren erfahren?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3370256149-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3370256149-label\" >\n\t\t\t\n<p>Die Preise variieren, da die Anzahl und Qualit\u00e4t der zu verblendenden Z\u00e4hne je nach den Anspr\u00fcchen der Menschen variiert. Sie k\u00f6nnen unsere Klinik besuchen, um klare Preisinformationen zu erhalten, oder unsere Zahn\u00e4rzte kontaktieren und ein kostenloses Vorgespr\u00e4ch vereinbaren. <\/p>\n\t\t<\/div>\n\t<\/div>\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1057918828 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_784670471\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1696587982\">\n\n\n\t<div id=\"col-1335871292\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row\"  id=\"row-1512033949\">\n\n\n\t<div id=\"col-1189453018\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"title-block\">\n<h4>ALBA DENT ADSP<\/h4>\n<h1>BEHANDLUNGEN<\/h1>\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-1449076646\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row row-small row-box-shadow-2 row-box-shadow-5-hover\"  id=\"row-1267640284\">\n\n\n\t<div id=\"col-2142101898\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1951027458\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/erstes-treffen\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-515970262\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>ERSTES TREFFEN<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-515970262 {\n  width: 87%;\n}\n#text-box-515970262 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1951027458 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-481937830\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1006101049\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/pour-les-enfants-pedodontie\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-1511675693\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>PEDODONTI<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1511675693 {\n  width: 87%;\n}\n#text-box-1511675693 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1006101049 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-980986347\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-749396404\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/mund-kiefer-und-gesichtschirurgie\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-1454268702\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Mund-, Kiefer- und Gesichtschirurgie<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1454268702 {\n  width: 87%;\n}\n#text-box-1454268702 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-749396404 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-833115184\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1707388531\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/zahnimplantat\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-1460079416\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Zahnimplantat<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1460079416 {\n  width: 87%;\n}\n#text-box-1460079416 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1707388531 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small row-box-shadow-2 row-box-shadow-5-hover\"  id=\"row-197037198\">\n\n\n\t<div id=\"col-1755021010\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-977210041\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/zahnfullung\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-48811198\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Zahnf\u00fcllung<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-48811198 {\n  width: 87%;\n}\n#text-box-48811198 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-977210041 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-135447406\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-796182424\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/zahnextraktion\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-660863181\" class=\"text-box banner-layer x50 md-x50 lg-x50 y95 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Zahnextraktion<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-660863181 {\n  width: 87%;\n}\n#text-box-660863181 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-796182424 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-471879025\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1841090390\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/zahnaufhellung\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-1850247030\" class=\"text-box banner-layer x50 md-x50 lg-x50 y100 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Zahnaufhellung<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1850247030 {\n  width: 87%;\n}\n#text-box-1850247030 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1841090390 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1733312753\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-292581326\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/wurzelbehandlung\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-763046500\" class=\"text-box banner-layer x50 md-x50 lg-x50 y100 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Wurzelbehandlung<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-763046500 {\n  width: 87%;\n}\n#text-box-763046500 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-292581326 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small row-box-shadow-2 row-box-shadow-5-hover\"  id=\"row-1664417933\">\n\n\n\t<div id=\"col-1130568862\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-655536960\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/weisheitszahnextraktion\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-375424051\" class=\"text-box banner-layer x50 md-x50 lg-x50 y100 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Weisheitszahnextraktion<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-375424051 {\n  width: 87%;\n}\n#text-box-375424051 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-655536960 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1815601535\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1547515332\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/kaiserin-krone\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-1924792562\" class=\"text-box banner-layer x50 md-x50 lg-x50 y100 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Kaiserin-Krone<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1924792562 {\n  width: 87%;\n}\n#text-box-1924792562 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1547515332 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1401850770\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-58920533\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/zirkonium-krone\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-1655097065\" class=\"text-box banner-layer x5 md-x50 lg-x50 y100 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Zirkonium Krone<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1655097065 {\n  width: 87%;\n}\n#text-box-1655097065 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-58920533 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-282705850\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1189783467\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                                                \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/\" ><div class=\"fill banner-link\"><\/div><\/a>            \n\n   <div id=\"text-box-302391685\" class=\"text-box banner-layer x50 md-x50 lg-x50 y100 md-y95 lg-y95 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n<h2 class=\"uppercase\"><strong>Zirkonium Krone<\/strong><\/h2>\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-302391685 {\n  width: 87%;\n}\n#text-box-302391685 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1189783467 {\n  padding-top: 450px;\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_784670471 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(243, 243, 243);\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":1215,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-1319","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Porzellan-Furnier | Alba Dent Pendik Di\u015f Klini\u011fi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Porzellan-Furnier | Alba Dent Pendik Di\u015f Klini\u011fi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/\" \/>\n<meta property=\"og:site_name\" content=\"Alba Dent Pendik Di\u015f Klini\u011fi\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-31T12:21:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.albadental.com.tr\/wp-content\/uploads\/2022\/07\/alba123.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"812\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/\",\"url\":\"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/\",\"name\":\"Porzellan-Furnier | Alba Dent Pendik Di\u015f Klini\u011fi\",\"isPartOf\":{\"@id\":\"https:\/\/www.albadental.com.tr\/#website\"},\"datePublished\":\"2022-07-21T15:43:20+00:00\",\"dateModified\":\"2023-07-31T12:21:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\/\/www.albadental.com.tr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Behandlungen\",\"item\":\"https:\/\/www.albadental.com.tr\/de\/behandlungen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Porzellan-Furnier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.albadental.com.tr\/#website\",\"url\":\"https:\/\/www.albadental.com.tr\/\",\"name\":\"Alba Dent Pendik Di\u015f Klini\u011fi\",\"description\":\"Pendik &amp; Kurtk\u00f6y Di\u015f Klini\u011fi\",\"publisher\":{\"@id\":\"https:\/\/www.albadental.com.tr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.albadental.com.tr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.albadental.com.tr\/#organization\",\"name\":\"Alba Dent - Pendik & Kurtk\u00f6y Di\u015f Klini\u011fi\",\"url\":\"https:\/\/www.albadental.com.tr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.albadental.com.tr\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.albadental.com.tr\/wp-content\/uploads\/2022\/07\/logo-1-1-1.png\",\"contentUrl\":\"http:\/\/www.albadental.com.tr\/wp-content\/uploads\/2022\/07\/logo-1-1-1.png\",\"width\":438,\"height\":74,\"caption\":\"Alba Dent - Pendik & Kurtk\u00f6y Di\u015f Klini\u011fi\"},\"image\":{\"@id\":\"https:\/\/www.albadental.com.tr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/albadent.dis\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Porzellan-Furnier | Alba Dent Pendik Di\u015f Klini\u011fi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/","og_locale":"de_DE","og_type":"article","og_title":"Porzellan-Furnier | Alba Dent Pendik Di\u015f Klini\u011fi","og_url":"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/","og_site_name":"Alba Dent Pendik Di\u015f Klini\u011fi","article_modified_time":"2023-07-31T12:21:07+00:00","og_image":[{"width":1000,"height":812,"url":"https:\/\/www.albadental.com.tr\/wp-content\/uploads\/2022\/07\/alba123.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/","url":"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/","name":"Porzellan-Furnier | Alba Dent Pendik Di\u015f Klini\u011fi","isPartOf":{"@id":"https:\/\/www.albadental.com.tr\/#website"},"datePublished":"2022-07-21T15:43:20+00:00","dateModified":"2023-07-31T12:21:07+00:00","breadcrumb":{"@id":"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.albadental.com.tr\/de\/behandlungen\/porzellan-furnier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/www.albadental.com.tr\/de\/"},{"@type":"ListItem","position":2,"name":"Behandlungen","item":"https:\/\/www.albadental.com.tr\/de\/behandlungen\/"},{"@type":"ListItem","position":3,"name":"Porzellan-Furnier"}]},{"@type":"WebSite","@id":"https:\/\/www.albadental.com.tr\/#website","url":"https:\/\/www.albadental.com.tr\/","name":"Alba Dent Pendik Di\u015f Klini\u011fi","description":"Pendik &amp; Kurtk\u00f6y Di\u015f Klini\u011fi","publisher":{"@id":"https:\/\/www.albadental.com.tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.albadental.com.tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.albadental.com.tr\/#organization","name":"Alba Dent - Pendik & Kurtk\u00f6y Di\u015f Klini\u011fi","url":"https:\/\/www.albadental.com.tr\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.albadental.com.tr\/#\/schema\/logo\/image\/","url":"http:\/\/www.albadental.com.tr\/wp-content\/uploads\/2022\/07\/logo-1-1-1.png","contentUrl":"http:\/\/www.albadental.com.tr\/wp-content\/uploads\/2022\/07\/logo-1-1-1.png","width":438,"height":74,"caption":"Alba Dent - Pendik & Kurtk\u00f6y Di\u015f Klini\u011fi"},"image":{"@id":"https:\/\/www.albadental.com.tr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/albadent.dis\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.albadental.com.tr\/de\/wp-json\/wp\/v2\/pages\/1319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.albadental.com.tr\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.albadental.com.tr\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.albadental.com.tr\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.albadental.com.tr\/de\/wp-json\/wp\/v2\/comments?post=1319"}],"version-history":[{"count":2,"href":"https:\/\/www.albadental.com.tr\/de\/wp-json\/wp\/v2\/pages\/1319\/revisions"}],"predecessor-version":[{"id":2498,"href":"https:\/\/www.albadental.com.tr\/de\/wp-json\/wp\/v2\/pages\/1319\/revisions\/2498"}],"up":[{"embeddable":true,"href":"https:\/\/www.albadental.com.tr\/de\/wp-json\/wp\/v2\/pages\/1215"}],"wp:attachment":[{"href":"https:\/\/www.albadental.com.tr\/de\/wp-json\/wp\/v2\/media?parent=1319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}